{"id":1547,"date":"2024-06-07T16:02:16","date_gmt":"2024-06-07T19:02:16","guid":{"rendered":"https:\/\/7midias.com.br\/michelle-borges\/?p=1547"},"modified":"2024-06-10T17:46:39","modified_gmt":"2024-06-10T20:46:39","slug":"cuidando-da-sua-imagem-pessoal","status":"publish","type":"post","link":"https:\/\/7midias.com.br\/michelle-borges\/cuidando-da-sua-imagem-pessoal\/","title":{"rendered":"Cuidando da sua Imagem Pessoal"},"content":{"rendered":"<div class=\"elementor-element elementor-element-50a5fed elementor-widget elementor-widget-image\" data-id=\"50a5fed\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n<div class=\"elementor-widget-container\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large wp-image-197\" src=\"https:\/\/sejaseumelhorresultado.com.br\/wp-content\/uploads\/2019\/06\/imagem-e-vestimenta.png\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" srcset=\"https:\/\/sejaseumelhorresultado.com.br\/wp-content\/uploads\/2019\/06\/imagem-e-vestimenta.png 500w, https:\/\/sejaseumelhorresultado.com.br\/wp-content\/uploads\/2019\/06\/imagem-e-vestimenta-300x172.png 300w, https:\/\/sejaseumelhorresultado.com.br\/wp-content\/uploads\/2019\/06\/imagem-e-vestimenta-292x169.png 292w\" alt=\"\" width=\"500\" height=\"287\" \/><img loading=\"lazy\" decoding=\"async\" class=\"attachment-medium size-medium wp-image-195\" src=\"https:\/\/sejaseumelhorresultado.com.br\/wp-content\/uploads\/2019\/06\/cart%C3%A3o-de-visitas-300x300.png\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/sejaseumelhorresultado.com.br\/wp-content\/uploads\/2019\/06\/cart\u00e3o-de-visitas-300x300.png 300w, https:\/\/sejaseumelhorresultado.com.br\/wp-content\/uploads\/2019\/06\/cart\u00e3o-de-visitas.png 500w, https:\/\/sejaseumelhorresultado.com.br\/wp-content\/uploads\/2019\/06\/cart\u00e3o-de-visitas-169x169.png 169w\" alt=\"\" width=\"300\" height=\"300\" \/><\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-a78411b elementor-widget elementor-widget-text-editor\" data-id=\"a78411b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Assim como em um produto, nossa vestimenta e comportamento servem como marketing pessoal para destacar o conte\u00fado, que neste caso \u00e9 o que temos a oferecer.<\/p>\n<p>A boa apar\u00eancia \u00e9 capaz de demonstrar seriedade no trabalho auxiliando, inclusive, em novas conquistas. A boa impress\u00e3o do profissional \u00e9 o seu cart\u00e3o de visitas.<\/p>\n<p>Esta primeira impress\u00e3o \u00e9 o que far\u00e1 a outra pessoa direcionar a aten\u00e7\u00e3o de forma positiva ou negativa e observar o que temos a agregar (ou n\u00e3o), por isso, \u00e9 importante estarmos adequados aos ambientes que transitamos diariamente.<\/p>\n<p>No meio empresarial, funciona da mesma maneira, diariamente somos observados por nossos superiores, pares, colegas de outras equipes e mesmo por profissionais de outras empresas que transitam em \u00e1reas comuns nos pr\u00e9dios comerciais.<\/p>\n<p>Muitas vezes nossa apresenta\u00e7\u00e3o interfere em decis\u00f5es que os gestores precisam tomar em rela\u00e7\u00e3o a nossa posi\u00e7\u00e3o, como por exemplo, convidar para uma reuni\u00e3o com cliente, fornecedor, diretoria ou mesmo assumir cargos de destaque.<\/p>\n<p>Cada profiss\u00e3o e segmento exige um tipo de vestimenta, sendo assim \u00e9 muito importante ficar de olho no manual de conduta e respeitar as normas.<\/p>\n<p>Lembre-se que o profissional \u00e9 formado por um conjunto de caracter\u00edsticas, por\u00e9m, a apar\u00eancia \u00e9 o primeiro atrativo!<\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-d34665c elementor-widget elementor-widget-heading\" data-id=\"d34665c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Dicas Importantes<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-126c04b elementor-widget elementor-widget-image\" data-id=\"126c04b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n<div class=\"elementor-widget-container\"><img decoding=\"async\" class=\"aligncenter\" title=\"blur-1850082_960_720\" src=\"https:\/\/sejaseumelhorresultado.com.br\/wp-content\/uploads\/2019\/06\/blur-1850082_960_720-480x300.jpg\" alt=\"blur-1850082_960_720\" \/><\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-137e42d elementor-widget elementor-widget-text-editor\" data-id=\"137e42d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>\u2014 Harmonize as cores para adequar o traje e evitar misturas chamativas.<br \/>\n\u2014 Sapatos escuros e bem engraxados com meias neutras.<br \/>\n\u2014 Gravatas neutras e com um n\u00f3 bem feito. Evite misturar estampas de gravatas com blusas estampadas.<br \/>\n\u2014 Barbas bem feitas, aparadas e cuidadas.<br \/>\n\u2014 Sapato social com salto m\u00e9dio ou sapatos e sapatilhas discretas e fechadas. Evite sand\u00e1lias de borracha e rasteirinhas abertas.<br \/>\n\u2014 Utilize acess\u00f3rios discretos e evite pulseiras barulhentas e brinco grande.<br \/>\n\u2014 Saias e vestidos (social) devem estar no m\u00e1ximo at\u00e9 dois dedos acima do joelho.<br \/>\n\u2014 N\u00e3o utilize decotes e transpar\u00eancias.<br \/>\n\u2014 N\u00e3o utilize roupas muito justas e cal\u00e7a legging.<br \/>\n\u2014 Maquiagem discreta.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Assim como em um produto, nossa vestimenta e comportamento servem como marketing pessoal para destacar o conte\u00fado, que neste caso \u00e9 o que temos a oferecer. A boa apar\u00eancia \u00e9&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1594,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-1547","post","type-post","status-publish","format-standard","has-post-thumbnail","category-desenvolvimento-pessoal"],"_links":{"self":[{"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/posts\/1547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/comments?post=1547"}],"version-history":[{"count":0,"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/posts\/1547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/media\/1594"}],"wp:attachment":[{"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/media?parent=1547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/categories?post=1547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7midias.com.br\/michelle-borges\/wp-json\/wp\/v2\/tags?post=1547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}